﻿{"id":7984,"date":"2025-10-30T14:08:33","date_gmt":"2025-10-30T13:08:33","guid":{"rendered":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/?p=7984"},"modified":"2025-10-30T14:08:33","modified_gmt":"2025-10-30T13:08:33","slug":"publikationsdaten-der-universitaet-unter-einem-dach-die-neue-erfurter-universitaetsbibliographie","status":"publish","type":"post","link":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/publikationsdaten-der-universitaet-unter-einem-dach-die-neue-erfurter-universitaetsbibliographie\/","title":{"rendered":"Publikationsdaten der Universit\u00e4t unter einem Dach: die neue Erfurter Universit\u00e4tsbibliographie"},"content":{"rendered":"<p>F\u00fcr Anfang 2026 plant die Universit\u00e4tsbibliothek, die neue Erfurter Universit\u00e4tsbibliographie freizuschalten. Mit diesem ersten Blogbeitrag m\u00f6chten wir grundlegende Informationen zur neuen zentralen Erfassungs- und Nachweisplattform f\u00fcr wissenschaftliche Publikationen der Universit\u00e4t Erfurt geben \u2011 und nat\u00fcrlich wollen wir auch Neugier wecken. Die Freischaltungsphase begleiten wir durch weitere in loser Folge erscheinende Blogbeitr\u00e4ge. Bei Interesse lohnt es sich also ganz besonders, das \u201eLesezeichen\u201c in den n\u00e4chsten Wochen und Monaten zu verfolgen.<\/p>\n<p>Die Bibliographie ist im Rahmen des th\u00fcringenweiten Projekts \u201eTh\u00fcringer Universit\u00e4tsbibliographie\u201c entstanden, mit dem gemeinschaftlich einige wesentliche Ziele verfolgt wurden:<\/p>\n<ul>\n<li>Forschende so weit wie m\u00f6glich von aufwendigen Meldeverfahren zu entlasten, indem automatisierte Verfahren f\u00fcr Publikationserfassung und -nachweis genutzt werden,<\/li>\n<li>M\u00f6glichkeiten f\u00fcr den Abruf und die Nachnutzung individueller Publikationslisten aus dem System heraus zu schaffen,<\/li>\n<li>durch kooperative Entwicklung Kosten zu minimieren,<\/li>\n<li>einheitliche Standards f\u00fcr Th\u00fcringen zu schaffen,<\/li>\n<li>Schnittstellen zu anderen in Th\u00fcringen eingesetzten Systemen (z. B. Forschungsinformationssystemen) zu nutzen,<\/li>\n<li>den Open-Access-Status von Publikationen sichtbar zu machen.<\/li>\n<\/ul>\n<p>Details zu den konkreten Funktionalit\u00e4ten der Bibliographie und zu den n\u00e4chsten Schritten der Einf\u00fchrung folgen in den n\u00e4chsten Wochen. Ein kleiner Hinweis schon jetzt: Mitmachen ist m\u00f6glich\u2026<\/p>\n<p><em><a href=\"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-content\/uploads\/2025\/10\/Thunibib_Bildschirm.png\"><img loading=\"lazy\" class=\"aligncenter wp-image-7986\" src=\"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-content\/uploads\/2025\/10\/Thunibib_Bildschirm.png\" alt=\"\" width=\"912\" height=\"513\" srcset=\"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-content\/uploads\/2025\/10\/Thunibib_Bildschirm-850x478.png 850w, https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-content\/uploads\/2025\/10\/Thunibib_Bildschirm-1200x675.png 1200w, https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-content\/uploads\/2025\/10\/Thunibib_Bildschirm-250x141.png 250w\" sizes=\"(max-width: 912px) 100vw, 912px\" \/><\/a><\/em><em>Redaktionsteam Erfurter Universit\u00e4tsbibliographie<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr Anfang 2026 plant die Universit\u00e4tsbibliothek, die neue Erfurter Universit\u00e4tsbibliographie freizuschalten. Mit diesem ersten Blogbeitrag m\u00f6chten wir grundlegende Informationen zur neuen zentralen Erfassungs- und Nachweisplattform f\u00fcr wissenschaftliche Publikationen der Universit\u00e4t Erfurt geben \u2011 und nat\u00fcrlich wollen wir auch Neugier wecken. <a class=\"more-link\" href=\"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/publikationsdaten-der-universitaet-unter-einem-dach-die-neue-erfurter-universitaetsbibliographie\/\">weiterlesen  <span class=\"screen-reader-text\">  Publikationsdaten der Universit\u00e4t unter einem Dach: die neue Erfurter Universit\u00e4tsbibliographie<\/span><span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[481,96],"tags":[482],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts\/7984"}],"collection":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/comments?post=7984"}],"version-history":[{"count":5,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts\/7984\/revisions"}],"predecessor-version":[{"id":7990,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts\/7984\/revisions\/7990"}],"wp:attachment":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/media?parent=7984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/categories?post=7984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/tags?post=7984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}