﻿{"id":4123,"date":"2020-04-23T11:23:09","date_gmt":"2020-04-23T09:23:09","guid":{"rendered":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/?p=4123"},"modified":"2020-04-23T11:23:09","modified_gmt":"2020-04-23T09:23:09","slug":"fernleihe-eingeschraenkt-wieder-moeglich","status":"publish","type":"post","link":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/fernleihe-eingeschraenkt-wieder-moeglich\/","title":{"rendered":"Fernleihe eingeschr\u00e4nkt wieder m\u00f6glich"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"wp-image-4124 aligncenter\" src=\"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-content\/uploads\/2020\/04\/GVK_kopienbest.png\" alt=\"\" width=\"487\" height=\"210\" \/><\/p>\n<p><strong>Kostenfreier elektronischer Kopienversand bis zum 31. Mai 2020<\/strong><\/p>\n<p>Ab sofort haben Nutzerinnen und Nutzer der UB Erfurt mit einem Fernleihkonto wieder die M\u00f6glichkeit, den Kopienversand der Fernleihe zu nutzen.<\/p>\n<p>Im Rahmen des \u00a0\u201eCOVID-19 Notbetriebs\u201c k\u00f6nnen Sie Kopienbestellungen im\u00a0<a href=\"https:\/\/kxp.k10plus.de\/DB=2.1\/\">GBV-Verbundkatalog<\/a> aufgeben und erhalten Ihre Aufsatzbestellung direkt an die im Benutzerkonto hinterlegte E-Mail-Adresse. Diese elektronische Lieferm\u00f6glichkeit gilt voraussichtlich bis zum 31. Mai 2020.<br \/>\nBitte beachten Sie dabei, dass nicht alle Bibliotheken im Rahmen der Fernleihe lieferf\u00e4hig sind und daher eventuell nicht alle Bestellungen bearbeitet werden k\u00f6nnen oder es zu Verz\u00f6gerungen kommen kann.<\/p>\n<p>Bestellt werden k\u00f6nnen<\/p>\n<ul>\n<li>Teilkopien aus B\u00fcchern (max. 10%)<\/li>\n<li>Artikel aus wissenschaftlichen und Fachzeitschriften<\/li>\n<\/ul>\n<p>Die Kopienbestellung ist im Rahmen des Notbetriebs kostenfrei, die \u00fcbliche Fernleihgeb\u00fchr pro Bestellung entf\u00e4llt.<\/p>\n<p>Bei R\u00fcckfragen wenden Sie sich bitte an fernleihe.ub@uni-erfurt.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kostenfreier elektronischer Kopienversand bis zum 31. Mai 2020 Ab sofort haben Nutzerinnen und Nutzer der UB Erfurt mit einem Fernleihkonto wieder die M\u00f6glichkeit, den Kopienversand der Fernleihe zu nutzen. Im Rahmen des \u00a0\u201eCOVID-19 Notbetriebs\u201c k\u00f6nnen Sie Kopienbestellungen im\u00a0GBV-Verbundkatalog aufgeben und <a class=\"more-link\" href=\"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/fernleihe-eingeschraenkt-wieder-moeglich\/\">weiterlesen  <span class=\"screen-reader-text\">  Fernleihe eingeschr\u00e4nkt wieder m\u00f6glich<\/span><span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":4124,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[96],"tags":[147],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts\/4123"}],"collection":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/comments?post=4123"}],"version-history":[{"count":4,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts\/4123\/revisions"}],"predecessor-version":[{"id":4128,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts\/4123\/revisions\/4128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/media\/4124"}],"wp:attachment":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/media?parent=4123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/categories?post=4123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/tags?post=4123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}