﻿{"id":2543,"date":"2018-06-07T10:53:55","date_gmt":"2018-06-07T08:53:55","guid":{"rendered":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/?p=2543"},"modified":"2018-06-07T10:53:55","modified_gmt":"2018-06-07T08:53:55","slug":"fair-play-in-der-bibliothek-garderobenschraenke","status":"publish","type":"post","link":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/fair-play-in-der-bibliothek-garderobenschraenke\/","title":{"rendered":"Fair play in der Bibliothek  &#8211;  Garderobenschr\u00e4nke"},"content":{"rendered":"<p>Es gibt 454 davon \u2013 trotzdem reichen die zur Verf\u00fcgung stehenden manchmal kaum aus: die Garderobenschr\u00e4nke im Foyer. Vor Betreten des Lesesaals werden Taschen und Jacken darin verstaut.<\/p>\n<p><img loading=\"lazy\" class=\"size-full wp-image-2544 aligncenter\" src=\"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-content\/uploads\/2018\/05\/garderobenschraenke.jpg\" alt=\"\" width=\"374\" height=\"300\" \/><\/p>\n<p>Das dient nicht nur dem Schutz des Bibliotheksbestandes, sondern ist auch eine Hilfe: man muss nicht sein ganzes Gep\u00e4ck in der Bibliothek umherschleppen. Allerdings sind die Schlie\u00dff\u00e4cher nicht dazu gedacht als Gep\u00e4ck-Depot f\u00fcr den ganzen Uni-Tag benutzt zu werden.<\/p>\n<p>Deshalb bitte beim Verlassen der Bibliothek das Fach wieder frei geben, damit andere die Chance haben, einen Platz f\u00fcr ihre Utensilien zu finden.<\/p>\n<p>\u00dcbrigens: Nach Schlie\u00dfung der Bibliothek am Abend werden die Schlie\u00dff\u00e4cher geleert. Eventuell noch darin verbliebene Dinge k\u00f6nnen am n\u00e4chsten Tag (Montag bis Freitag) ab 10:00 Uhr als Fundsachen an der Ausleihtheke abgeholt werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es gibt 454 davon \u2013 trotzdem reichen die zur Verf\u00fcgung stehenden manchmal kaum aus: die Garderobenschr\u00e4nke im Foyer. Vor Betreten des Lesesaals werden Taschen und Jacken darin verstaut. Das dient nicht nur dem Schutz des Bibliotheksbestandes, sondern ist auch eine <a class=\"more-link\" href=\"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/fair-play-in-der-bibliothek-garderobenschraenke\/\">weiterlesen  <span class=\"screen-reader-text\">  Fair play in der Bibliothek  &#8211;  Garderobenschr\u00e4nke<\/span><span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[236,235],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts\/2543"}],"collection":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/comments?post=2543"}],"version-history":[{"count":1,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts\/2543\/revisions"}],"predecessor-version":[{"id":2545,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/posts\/2543\/revisions\/2545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/media\/2544"}],"wp:attachment":[{"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/media?parent=2543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/categories?post=2543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.uni-erfurt.de\/bibliothek\/blog\/wp-json\/wp\/v2\/tags?post=2543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}